{"id":31,"count":2,"description":"","link":"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/","name":"Malaysia","slug":"malaysia","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Malaysia Archive - Notizen Von Unterwegs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malaysia Archive - Notizen Von Unterwegs\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/\" \/>\n<meta property=\"og:site_name\" content=\"Notizen Von Unterwegs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/\",\"url\":\"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/\",\"name\":\"Malaysia Archive - Notizen Von Unterwegs\",\"isPartOf\":{\"@id\":\"http:\/\/www.christianprinz.at\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\/\/www.christianprinz.at\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Malaysia\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.christianprinz.at\/blog\/#website\",\"url\":\"http:\/\/www.christianprinz.at\/blog\/\",\"name\":\"Notizen Von Unterwegs\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.christianprinz.at\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Malaysia Archive - Notizen Von Unterwegs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/","og_locale":"de_DE","og_type":"article","og_title":"Malaysia Archive - Notizen Von Unterwegs","og_url":"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/","og_site_name":"Notizen Von Unterwegs","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/","url":"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/","name":"Malaysia Archive - Notizen Von Unterwegs","isPartOf":{"@id":"http:\/\/www.christianprinz.at\/blog\/#website"},"breadcrumb":{"@id":"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"http:\/\/www.christianprinz.at\/blog\/category\/malaysia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/www.christianprinz.at\/blog\/"},{"@type":"ListItem","position":2,"name":"Malaysia"}]},{"@type":"WebSite","@id":"http:\/\/www.christianprinz.at\/blog\/#website","url":"http:\/\/www.christianprinz.at\/blog\/","name":"Notizen Von Unterwegs","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.christianprinz.at\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"http:\/\/www.christianprinz.at\/blog\/wp-json\/wp\/v2\/categories\/31"}],"collection":[{"href":"http:\/\/www.christianprinz.at\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.christianprinz.at\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.christianprinz.at\/blog\/wp-json\/wp\/v2\/posts?categories=31"},{"href":"http:\/\/www.christianprinz.at\/blog\/wp-json\/wp\/v2\/media?categories=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}